{"id":5118,"date":"2022-10-06T17:34:22","date_gmt":"2022-10-06T15:34:22","guid":{"rendered":"https:\/\/editorialperegrino.com\/blog\/?p=5118"},"modified":"2022-10-06T18:22:50","modified_gmt":"2022-10-06T16:22:50","slug":"una-gran-multitud","status":"publish","type":"post","link":"https:\/\/editorialperegrino.com\/blog\/una-gran-multitud\/","title":{"rendered":"Una gran multitud"},"content":{"rendered":"<p align=\"justify\">Apocalipsis cap\u00edtulo 7 vers\u00edculo 9 nos describe el Cielo en t\u00e9rminos de una gran multitud de todas las naciones y tribus y pueblos y lenguas; y varias veces este \u00faltimo fin de semana he pensado en esta descripci\u00f3n.<\/p>\n<p align=\"justify\">La misi\u00f3n con la que trabajamos mi esposa y yo, European Mission Fellowship, ha celebrado estos d\u00edas, aqu\u00ed en Ciudad Real, su conferencia internacional para todos sus obreros. Ciento tres personas, de catorce pa\u00edses europeos diferentes, reunidas bajo un mismo techo y usando el ingl\u00e9s como lengua franca.<\/p>\n<p align=\"justify\">Muchos de nosotros no nos conoc\u00edamos hasta que nos reunimos el jueves por la tarde. Algunos solo por Zoom, y nos sorprendimos al ver la altura de m\u00e1s de uno. Unos desconocidos, pero unidos, no solo por pertenecer a la misma misi\u00f3n, sino por compartir la misma visi\u00f3n: anunciar el evangelio en este continente europeo que amamos.<\/p>\n<p align=\"justify\">Para muchas personas, la palabra \u00abmisi\u00f3n\u00bb sugiere la idea de un religioso que se desplaza a un pa\u00eds del llamado \u00abtercer mundo\u00bb para ayudar con alg\u00fan proyecto de desarrollo, como la alfabetizaci\u00f3n, instalaciones m\u00e9dicas o proveer agua potable.<\/p>\n<p align=\"justify\">Y en este sentido se podr\u00eda cuestionar el porqu\u00e9 de una misi\u00f3n que trabaja exclusivamente en Europa, siendo del \u00abprimer mundo\u00bb. Sin embargo, cuando usamos la definici\u00f3n b\u00edblica de las misiones <span style=\"color: #4d5156;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: small;\">\u2014<\/span><\/span><\/span>ser enviado por el Se\u00f1or para predicar el evangelio y hacer disc\u00edpulos<span style=\"color: #4d5156;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: small;\">\u2014<\/span><\/span><\/span>, no podemos hacer otra cosa que concluir que Europa es un campo misionero en toda regla.<\/p>\n<p align=\"justify\">Al recorrer las iglesias del Reino Unido antes de trasladarnos a Espa\u00f1a en 1991, a veces tuvimos que justificar el hecho de \u00abignorar\u00bb pa\u00edses y continentes tradicionalmente receptores del esfuerzo misionero, como si no quisi\u00e9ramos alejarnos mucho de nuestro pa\u00eds natal. Lo que pasa es que Europa es el continente con menos cristianos del mundo, solo un 2,5%. Solo el pa\u00eds de China tiene cinco veces m\u00e1s evang\u00e9licos que toda Europa, y Nigeria supera a Europa con creces tambi\u00e9n, hasta tres veces.<\/p>\n<p align=\"justify\">Amigos, si le\u00e9is esto desde Europa, vivimos en un continente que todav\u00eda necesita el evangelio. Igual nuestras iglesias son peque\u00f1as y, si est\u00e1s en Espa\u00f1a, probablemente dependen de ayuda misionera para existir y seguir adelante. Pero no por eso dejemos de fijar nuestra mirada en los de nuestra \u00abSamaria\u00bb europea, que est\u00e1n al lado, y que no han o\u00eddo el evangelio.<\/p>\n<p align=\"justify\">Ninguna iglesia es demasiado peque\u00f1a para poder apoyar a un misionero. Todo el mundo puede orar por un obrero en Europa. Hasta las ofrendas m\u00e1s peque\u00f1as pueden contribuir a avanzar la obra de Dios. He visto iglesias que dependen de la ayuda misionera tambi\u00e9n dar apoyo a otros, y he visto como estas iglesias crecen y maduran por ello.<\/p>\n<p align=\"justify\">Y no digo que ignoremos a los dem\u00e1s continentes con sus grandes necesidades; simplemente que no pensemos que el valor de las misiones est\u00e9 en la distancia que recorramos. Europa <span style=\"color: #4d5156;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: small;\">\u2014<\/span><\/span><\/span>s\u00ed, esta Europa que dio la Reforma al mundo<span style=\"color: #4d5156;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: small;\">\u2014<\/span><\/span><\/span> necesita el evangelio m\u00e1s que nunca. Y cuando predicamos el evangelio a nuestros vecinos europeos y se convierten, estamos contribuyendo a que esta imagen en Apocalipsis 7:9,10 se haga realidad.<\/p>\n<p align=\"justify\">\u00ab<i>Y despu\u00e9s de eso mir\u00e9, y he aqu\u00ed una gran multitud, la cual nadie pod\u00eda contar, de todas naciones y tribus y pueblos y lenguas, que estaban delante del trono y en presencia del Cordero, vestidos de ropas blancas, y con palmas en las manos; clamaban a gran voz, diciendo: La salvaci\u00f3n pertenece a nuestro Dios que est\u00e1 sentado en el trono, y al Cordero<\/i>\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apocalipsis cap\u00edtulo 7 vers\u00edculo 9 nos describe el Cielo en t\u00e9rminos de una gran multitud de todas las naciones y tribus y pueblos y lenguas; y varias veces este \u00faltimo&#8230;<\/p>\n","protected":false},"author":4,"featured_media":5123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[5],"tags":[220,541,136,543,542],"_links":{"self":[{"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/posts\/5118"}],"collection":[{"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/comments?post=5118"}],"version-history":[{"count":2,"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/posts\/5118\/revisions"}],"predecessor-version":[{"id":5121,"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/posts\/5118\/revisions\/5121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/media\/5123"}],"wp:attachment":[{"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/media?parent=5118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/categories?post=5118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/tags?post=5118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}