{"id":4023,"date":"2015-09-30T14:25:32","date_gmt":"2015-09-30T14:25:32","guid":{"rendered":"http:\/\/editorialperegrino.com\/?p=4023"},"modified":"2015-09-30T14:37:57","modified_gmt":"2015-09-30T14:37:57","slug":"dos-hombres-y-una-corona","status":"publish","type":"post","link":"https:\/\/editorialperegrino.com\/blog\/dos-hombres-y-una-corona\/","title":{"rendered":"Dos hombres y una corona"},"content":{"rendered":"<h3 style=\"text-align: justify;\">Dos hombres y una corona<\/h3>\n<p style=\"text-align: justify;\">Dos reconocimientos, dos pa\u00edses, dos continentes, dos \u00e9pocas y, por \u00faltimo, dos hombres: <strong>hablamos de Mart\u00edn Lutero y Billy Graham<\/strong>. Aunque no suelen o\u00edrse sus nombres en una misma oraci\u00f3n, en estos \u00faltimos d\u00edas Protestante Digital ha anunciado reconocimientos oficiales a estos dos siervos de Dios.<\/p>\n<h3 style=\"text-align: justify;\">Mart\u00edn Lutero<\/h3>\n<p style=\"text-align: justify;\">Mart\u00edn Lutero, hombre usado por el Se\u00f1or como parte del gran movimiento de la Reforma del siglo XVI, <strong>ya tiene una plaza que lleva su nombre en la ciudad de Roma.<\/strong> Con buenas vistas al Vaticano y con el visto bueno de la Iglesia cat\u00f3lica romana, la <em>Piazza Martin Lutero<\/em> luce su cartel con la explicaci\u00f3n para los que no lo saben de que Lutero fue \u00abte\u00f3logo alem\u00e1n de la Reforma\u00bb. As\u00ed que la ciudad que quinientos a\u00f1os atr\u00e1s inspir\u00f3 al monje germano a rechazar las indulgencias le da su propia indulgencia personal.<\/p>\n<h3 style=\"text-align: justify;\">Billy Graham<\/h3>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/editorialperegrino.com\/blog\/dos-hombres-y-una-corona\/billy-graham-web\/\" rel=\"attachment wp-att-4029\"><img loading=\"lazy\" class=\"alignright wp-image-4029 size-thumbnail\" src=\"https:\/\/editorialperegrino.com\/blog\/wp-content\/uploads\/Billy-Graham-WEB-150x150.jpg\" alt=\"Billy-Graham-WEB\" width=\"150\" height=\"150\" srcset=\"https:\/\/editorialperegrino.com\/blog\/wp-content\/uploads\/Billy-Graham-WEB-150x150.jpg 150w, https:\/\/editorialperegrino.com\/blog\/wp-content\/uploads\/Billy-Graham-WEB-228x228.jpg 228w, https:\/\/editorialperegrino.com\/blog\/wp-content\/uploads\/Billy-Graham-WEB.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>Billy Graham, el destacado evangelista del siglo XX, nacido en una granja humilde en Carolina del Norte (Estados Unidos), <strong>ha llegado a visitar 185 pa\u00edses con el prop\u00f3s<\/strong><strong>ito <\/strong><strong>de anunciar el evangelio de salvaci\u00f3n en Jesucristo.<\/strong> Conocido por sus campa\u00f1as evangel\u00edsticas a gran escala, ha sido o\u00eddo por millones de personas durante su vida, desde los m\u00e1s humildes hasta los m\u00e1s poderosos. Amigo de presidentes, <strong>hay quien dice que lleg\u00f3 a ser el segundo hombre religioso m\u00e1s poderoso en el plan<\/strong><strong>eta despu\u00e9s del Papa.<\/strong> Y ahora su estatua va a lucirse en el Capitolio estadounidense, la sede f\u00edsica del poder legislativo americano que alberga las dos c\u00e1maras del Congreso.<\/p>\n<h3 style=\"text-align: justify;\">Dos siervos de Dios<\/h3>\n<p style=\"text-align: justify;\">Dos hombres, pues, que <strong>reciben un reconocimiento p\u00fablico, oficial, por sus labores cristianas.<\/strong> Dos hombres no exentos de pol\u00e9mica, incluso dentro de c\u00edrculos evang\u00e9licos y reformados. <strong>En el caso de Lutero ser\u00eda su doctrina de la consustanciaci\u00f3n o su antisemitismo<\/strong>, mientras que <strong>en el caso de Graham hay quien apunta hacia su ecumenismo y su \u00abevangelio f\u00e1cil\u00bb.<\/strong> Todos tenemos nuestras flaquezas, \u00bfverdad?<\/p>\n<p style=\"text-align: justify;\">Por un lado, podemos decir que <strong>es de justicia que hombres que hicieron tanto sean reconocidos con honores.<\/strong> Hay tanta gente pagana que recibe aplausos y fama a pesar de \u2013y, muchas veces, a causa de\u2013 su inmoralidad, impiedad y maldad. Ya est\u00e1 bien que de vez en cuando los buenos sean reconocidos como tales. M\u00e1xime si <strong>durante su vida han sido objeto de insultos, desprecio y persecuci\u00f3n.<\/strong><\/p>\n<h3 style=\"text-align: justify;\">Solo a Dios la gloria<\/h3>\n<p style=\"text-align: justify;\">Por otro lado, los creyentes <strong>no tenemos que buscar el reconocimiento de nadie m\u00e1s que de nuestro Padre celestial.<\/strong> <strong>Todo debe ser para su gloria y no para la nuestra.<\/strong> Es cierto que al hacer las cosas para la gloria de Dios, muchas veces nuestro trabajo es admirado por los inconversos. Pero si recibimos o no el reconocimiento de nuestros iguales en la tierra es indiferente; <strong>lo que nos importa, nos conmueve y nos constri\u00f1e es escuchar alg\u00fan d\u00eda aquellas palabras: \u00abBien, buen siervo y fiel, entra\u00bb.<\/strong> Recibiremos nuestra corona all\u00ed en la presencia de Dios y luego la echaremos a los pies del Rey de reyes. Si no voy a recibir esta corona, ninguna plaza a mi nombre o estatua en mi honor me sirve de nada.<\/p>\n<p style=\"text-align: justify;\">Por cierto, la estatua de Billy Graham no podr\u00e1 ser instalada en el Capitolio hasta despu\u00e9s de su muerte. Para aquel entonces ya tendr\u00e1 su galard\u00f3n. Lutero ya tiene su corona desde hace 469 a\u00f1os. Y a ti, <strong>\u00bfqu\u00e9 te espera tras tu muerte?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<img loading=\"lazy\" src=\"https:\/\/editorialperegrino.com\/blog\/wp-content\/uploads\/Mateo-252x300.jpg\" alt=\"OLYMPUS DIGITAL CAMERA\" width=\"63\" height=\"75\" \/><a href=\"https:\/\/editorialperegrino.com\/blog\/wp-content\/uploads\/Firma-MPH002.png\"><img loading=\"lazy\" src=\"https:\/\/editorialperegrino.com\/blog\/wp-content\/uploads\/Firma-MPH002-300x135.png\" alt=\"Firma-MPH002\" width=\"175\" height=\"85\" \/><\/a><\/p>\n<p>Mateo Hill \u00a0\u00a0<a title=\"director@editorialperegrino.com\" href=\"mailto:director@editorialperegrino.com\">administracion@editorialperegrino.com<\/a><\/p>\n<div style=\"text-align: justify;\"><em>Se permite la reproducci\u00f3n de este art\u00edculo siempre que se cite su procedencia y se indique la direcci\u00f3n de nuestra p\u00e1gina web.<\/em><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dos hombres y una corona Dos reconocimientos, dos pa\u00edses, dos continentes, dos \u00e9pocas y, por \u00faltimo, dos hombres: hablamos de Mart\u00edn Lutero y Billy Graham. Aunque no suelen o\u00edrse sus&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4024,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[5],"tags":[235,136,36,17,234,236],"_links":{"self":[{"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/posts\/4023"}],"collection":[{"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/comments?post=4023"}],"version-history":[{"count":0,"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/posts\/4023\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/media\/4024"}],"wp:attachment":[{"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/media?parent=4023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/categories?post=4023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/editorialperegrino.com\/blog\/wp-json\/wp\/v2\/tags?post=4023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}