{"id":118,"date":"2022-03-17T13:10:50","date_gmt":"2022-03-17T12:10:50","guid":{"rendered":"https:\/\/editorialperegrino.com\/apoyar\/peregrino-commentaries\/"},"modified":"2022-04-05T21:04:23","modified_gmt":"2022-04-05T19:04:23","slug":"peregrino-commentaries","status":"publish","type":"page","link":"https:\/\/editorialperegrino.com\/apoyar\/en\/peregrino-commentaries\/","title":{"rendered":"Peregrino Commentaries"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#d1d1ca&#8221; bg_image=&#8221;73&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; bottom_padding=&#8221;13%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; color_overlay=&#8221;#0a0a0a&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;350&#8243; bg_image_animation=&#8221;fade-in&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; shape_type=&#8221;mountains&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h1&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Comentarios Peregrino&#8221;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;800&#8243;][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h4&#8243; text_color=&#8221;#ffffff&#8221; button_color=&#8221;accent-color&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;Quiero colaborar&#8221; url=&#8221;#colaborar&#8221; margin_top=&#8221;30&#8243; padding_top=&#8221;20&#8243; padding_right=&#8221;40&#8243; padding_bottom=&#8221;20&#8243; padding_left=&#8221;40&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;90px&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f7f7f7&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;12%&#8221; bottom_padding=&#8221;9%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;about&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;73&#8243; background_image_position=&#8221;center center&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;zoom-out-reveal&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;300&#8243;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;300&#8243;][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;default&#8221; max_width=&#8221;450&#8243; font_size=&#8221;35&#8243;]<em>Project<\/em><\/p>\n<p><strong>Peregrino Commentaries<\/strong>[\/split_line_heading][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text max_width=&#8221;500&#8243;]Of all the books on a believers bookshelf, especially for a pastor, surely <strong>commentaries<\/strong> are amongst the most important..<\/p>\n<p>For many years here at Editorial Peregrino we have been publishing our highly valued <strong>\u201cPeregrino Commentaries\u201d<\/strong>, a series that exemplifies biblical exposition at its best. Combining depth with simplicity, these comentaries are highly appreciated, especially amongst pastors who have not had the opportunity of formal theological training. Written mainly by pastors and for pastors, we are constantly recieving requests for more of this kind of commentary, <strong>especially from South America and Cuba<\/strong>.<\/p>\n<p>Producing a series that covers the 66 biblical books takes time and money, especially if it is to be done with excellence. We do what we can to advance the series, but <strong>with your help we could do so much more.<\/strong><\/p>\n<p>To that end, we have opened an account where <strong>churches and individual believers can give<\/strong>towards this great work of providing much needed tools for the Spanish-speaking church.<\/p>\n<p>Titles in progressthat require sponsoring:<\/p>\n<p>\u2022 Romans (Stuart Olyott): translation, revision, type-setting and printing.<br \/>\n\u2022 Nahum (Jos\u00e9 Grau): translation, revision, type-setting and printing.<\/p>\n<p><strong><a href=\"https:\/\/editorialperegrino.com\/index.php?id_category=666&amp;controller=category\" target=\"_blank\" rel=\"noopener\">Consult<\/a><\/strong> existing titles in Spanish.[\/vc_column_text][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h4&#8243; text_color=&#8221;#f6a100&#8243; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;Quiero colaborar con este proyecto&#8221; url=&#8221;#colaborar&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;colaborar&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-7-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;185&#8243; background_image_position=&#8221;center center&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Make your donation&#8221; font_container=&#8221;tag:h2|text_align:left|color:%23dd9933&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1647518653378{margin-bottom: 10px !important;}&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Step 1&#8243; font_container=&#8221;tag:h5|text_align:left|color:%2333bbdd&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1586433878493{margin-bottom: 10px !important;}&#8221;][vc_custom_heading text=&#8221;Fill in the form&#8221; font_container=&#8221;tag:h3|text_align:left|color:%23bfbfbf&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1586362400500{margin-bottom: 10px !important;}&#8221;][vc_column_text]<div class=\"frm_forms  with_frm_style frm_style_estilos-formidable\" id=\"frm_form_3_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form \" id=\"form_dona-comentarios\"  >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_screen_reader\">Dona Comentarios<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"3\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_3\" id=\"frm_hide_fields_3\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"dona-comentarios\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_3\" name=\"frm_submit_entry_3\" value=\"f12a5e4ed4\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/apoyar\/en\/wp-json\/wp\/v2\/pages\/118\" \/><div id=\"frm_field_24_container\" class=\"frm_form_field frm_section_heading form-field  bg_form_2\">\r\n<h3 class=\"frm_pos_top frm_section_spacing\">Datos Personales<\/h3>\r\n\r\n\r\n<div id=\"frm_field_25_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_7zlf4a663767940\" id=\"field_7zlf4a663767940_label\" class=\"frm_primary_label\">Nombre Completo\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_7zlf4a663767940\" name=\"item_meta[25]\" value=\"\"  data-sectionid=\"24\" data-reqmsg=\"Este campo no puede estar en blanco.\" aria-required=\"true\" data-invmsg=\"Texto no es v\u00e1lido\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_26_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_14lrn9013b02f65\" id=\"field_14lrn9013b02f65_label\" class=\"frm_primary_label\">Correo electr\u00f3nico\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_14lrn9013b02f65\" name=\"item_meta[26]\" value=\"\"  data-sectionid=\"24\" data-reqmsg=\"Este campo no puede estar en blanco.\" aria-required=\"true\" data-invmsg=\"Correo electr\u00f3nico is invalid\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_27_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n    <label for=\"field_baue7e6da9f5b9f\" id=\"field_baue7e6da9f5b9f_label\" class=\"frm_primary_label\">Tel\u00e9fono\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <input type=\"tel\" id=\"field_baue7e6da9f5b9f\" name=\"item_meta[27]\" value=\"\"  data-sectionid=\"24\" data-invmsg=\"Tel\u00e9fono is invalid\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_28_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n    <label for=\"field_y668v0f5ea754e9\" id=\"field_y668v0f5ea754e9_label\" class=\"frm_primary_label\">Concepto\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_y668v0f5ea754e9\" name=\"item_meta[28]\" value=\"\"  data-sectionid=\"24\" data-invmsg=\"Texto no es v\u00e1lido\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<\/div>\n<div id=\"frm_field_30_container\" class=\"frm_form_field frm_section_heading form-field  bg_form_3\">\r\n<h3 class=\"frm_pos_top frm_section_spacing\">Donativo<\/h3>\r\n\r\n\r\n<div id=\"frm_field_31_container\" class=\"frm_form_field form-field  frm_top_container horizontal_radio frm_other_container\">\r\n    <div  id=\"field_ub7ui7b7e81d5c5_label\" class=\"frm_primary_label\">\u00bfQu\u00e9 cantidad quieres donar?\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/div>\r\n    <div class=\"frm_opt_container\" aria-labelledby=\"field_ub7ui7b7e81d5c5_label\" role=\"group\">\t\t<div class=\"frm_radio\" id=\"frm_radio_31-30-0\"><label for=\"field_ub7ui7b7e81d5c5-0\">\t\t<input type=\"radio\" name=\"item_meta[31]\" id=\"field_ub7ui7b7e81d5c5-0\" value=\"10\"\n\t\t   data-sectionid=\"30\" data-invmsg=\"\u00bfQu\u00e9 cantidad quieres donar? is invalid\" aria-invalid=\"false\"  \/> 10\u20ac<\/label><\/div>\n\t\t<div class=\"frm_radio\" id=\"frm_radio_31-30-1\"><label for=\"field_ub7ui7b7e81d5c5-1\">\t\t<input type=\"radio\" name=\"item_meta[31]\" id=\"field_ub7ui7b7e81d5c5-1\" value=\"20\"\n\t\t   data-sectionid=\"30\" data-invmsg=\"\u00bfQu\u00e9 cantidad quieres donar? is invalid\" aria-invalid=\"false\"  \/> 20\u20ac<\/label><\/div>\n\t\t<div class=\"frm_radio\" id=\"frm_radio_31-30-5\"><label for=\"field_ub7ui7b7e81d5c5-5\">\t\t<input type=\"radio\" name=\"item_meta[31]\" id=\"field_ub7ui7b7e81d5c5-5\" value=\"50\"\n\t\t   data-sectionid=\"30\" data-invmsg=\"\u00bfQu\u00e9 cantidad quieres donar? is invalid\" aria-invalid=\"false\"  \/> 50\u20ac<\/label><\/div>\n\t\t<div class=\"frm_radio\" id=\"frm_radio_31-30-6\"><label for=\"field_ub7ui7b7e81d5c5-6\">\t\t<input type=\"radio\" name=\"item_meta[31]\" id=\"field_ub7ui7b7e81d5c5-6\" value=\"100\"\n\t\t   data-sectionid=\"30\" data-invmsg=\"\u00bfQu\u00e9 cantidad quieres donar? is invalid\" aria-invalid=\"false\"  \/> 100\u20ac<\/label><\/div>\n\t\t<div class=\"frm_radio\" id=\"frm_radio_31-30-other_2\"><label for=\"field_ub7ui7b7e81d5c5-other_2\">\t\t<input type=\"radio\" name=\"item_meta[31]\" id=\"field_ub7ui7b7e81d5c5-other_2\" value=\"Otra cantidad\"\n\t\t   data-sectionid=\"30\" data-invmsg=\"\u00bfQu\u00e9 cantidad quieres donar? is invalid\" aria-invalid=\"false\"  \/> Otra cantidad<\/label><label for=\"field_ub7ui7b7e81d5c5-other_2-otext\" class=\"frm_screen_reader frm_hidden\">Otra cantidad<\/label><input type=\"text\" id=\"field_ub7ui7b7e81d5c5-other_2-otext\" class=\"frm_other_input frm_pos_none\"  name=\"item_meta[other][31]\" value=\"\" \/><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<\/div>\n<div id=\"frm_field_33_container\" class=\"frm_form_field  frm_html_container form-field\"><\/div>\n<div id=\"frm_field_34_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container vertical_radio\">\r\n    <div  id=\"field_qhtex68a6fc40f8_label\" class=\"frm_primary_label\">Legal\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/div>\r\n    <div class=\"frm_opt_container\" aria-labelledby=\"field_qhtex68a6fc40f8_label\" role=\"group\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_34-0\"><label for=\"field_qhtex68a6fc40f8-0\"><input type=\"checkbox\" name=\"item_meta[34][]\" id=\"field_qhtex68a6fc40f8-0\" value=\"He le\u00eddo y doy mi consentimiento a la &lt;a href=&quot;https:\/\/editorialperegrino.com\/index.php?id_cms=2&amp;controller=cms&quot; target=&quot;new&quot;&gt;Pol\u00edtica de Privacidad&lt;\/a&gt; *\"  data-reqmsg=\"Este campo no puede estar en blanco.\" aria-required=\"true\" data-invmsg=\"Legal is invalid\" aria-invalid=\"false\"   \/> He le\u00eddo y doy mi consentimiento a la <a href=\"https:\/\/editorialperegrino.com\/index.php?id_cms=2&amp;controller=cms\" target=\"new\">Pol\u00edtica de Privacidad<\/a> *<\/label><\/div>\n\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_34-1\"><label for=\"field_qhtex68a6fc40f8-1\"><input type=\"checkbox\" name=\"item_meta[34][]\" id=\"field_qhtex68a6fc40f8-1\" value=\"He le\u00eddo y acepto la &lt;a href=&quot;https:\/\/editorialperegrino.com\/index.php?id_cms=3&amp;controller=cms&quot; target=&quot;new&quot;&gt;Pol\u00edtica de las donaciones y devoluciones&lt;\/a&gt; *\"  data-reqmsg=\"Este campo no puede estar en blanco.\" aria-required=\"true\" data-invmsg=\"Legal is invalid\" aria-invalid=\"false\"   \/> He le\u00eddo y acepto la <a href=\"https:\/\/editorialperegrino.com\/index.php?id_cms=3&amp;controller=cms\" target=\"new\">Pol\u00edtica de las donaciones y devoluciones<\/a> *<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_35_container\" class=\"frm_form_field  frm_html_container form-field\">\n<div style=\"font-size: 12px;\">Editorial Peregrino le informa que los datos de car\u00e1cter personal que me proporciones rellenando el presente formulario ser\u00e1n tratados \u00fanicamente por Editorial Peregrino como responsable de esta web. Finalidad de la recogida y tratamiento de los datos personales: gestionar la solicitud de donativos que realizas mediante este formulario. Legitimaci\u00f3n: Consentimiento del interesado. Destinatarios: Heztner (proveedor de hosting) dentro de la UE. Ver pol\u00edtica de privacidad de hetzner. Podr\u00e1s ejercer tus derechos de acceso, rectificaci\u00f3n, limitaci\u00f3n y suprimir los datos en info@editorialperegrino.com as\u00ed como el derecho a presentar una reclamaci\u00f3n ante una autoridad de control.<\/div>\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t\t<div class=\"frm_verify\" aria-hidden=\"true\">\n\t\t\t\t<label for=\"frm_email_3\">\n\t\t\t\t\tIf you are human, leave this field blank.\t\t\t\t<\/label>\n\t\t\t\t<input type=\"text\" class=\"frm_verify\" id=\"frm_email_3\" name=\"frm_verify\" value=\"\"  \/>\n\t\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"jDPuqcBDVdgWZK5qY53IVjnY6T\/g8nRew2O1PA94CvI=\" \/><div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">Hacer Donativo<\/button>\r\n\r\n<\/div><\/div>\n<\/fieldset>\n<\/div>\n<\/form>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#d1d1ca&#8221; bg_image=&#8221;73&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; bottom_padding=&#8221;13%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; color_overlay=&#8221;#0a0a0a&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;350&#8243; bg_image_animation=&#8221;fade-in&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-118","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/editorialperegrino.com\/apoyar\/en\/wp-json\/wp\/v2\/pages\/118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/editorialperegrino.com\/apoyar\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/editorialperegrino.com\/apoyar\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/editorialperegrino.com\/apoyar\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/editorialperegrino.com\/apoyar\/en\/wp-json\/wp\/v2\/comments?post=118"}],"version-history":[{"count":1,"href":"https:\/\/editorialperegrino.com\/apoyar\/en\/wp-json\/wp\/v2\/pages\/118\/revisions"}],"predecessor-version":[{"id":119,"href":"https:\/\/editorialperegrino.com\/apoyar\/en\/wp-json\/wp\/v2\/pages\/118\/revisions\/119"}],"wp:attachment":[{"href":"https:\/\/editorialperegrino.com\/apoyar\/en\/wp-json\/wp\/v2\/media?parent=118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}